{"id":8,"date":"2022-02-22T07:58:25","date_gmt":"2022-02-22T07:58:25","guid":{"rendered":"https:\/\/www.sktperfectdemo.com\/themepack\/ecology\/?page_id=8"},"modified":"2026-06-25T06:53:20","modified_gmt":"2026-06-25T06:53:20","slug":"home","status":"publish","type":"page","link":"https:\/\/eleon-energy.com\/ro\/","title":{"rendered":"Home"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"8\" class=\"elementor elementor-8\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-750672c elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"750672c\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26c1d22\" data-id=\"26c1d22\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a50f66 elementor-widget__width-inherit elementor-widget elementor-widget-html\" data-id=\"7a50f66\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<!-- MasterSlider -->\n\t\t<div id=\"P_MS6a57bdf4e4e02\" class=\"master-slider-parent ms-parent-id-1\" style=\"\" >\n\n\t\t\t\n\t\t\t<!-- MasterSlider Main -->\n\t\t\t<div id=\"MS6a57bdf4e4e02\" class=\"master-slider ms-skin-light-6 round-skin\" >\n\t\t\t\t \t\t\t\t \n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/eleon-energy.com\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"poze_1 - Photo\" data-src=\"https:\/\/eleon-energy.com\/wp-content\/uploads\/2023\/05\/poze_1-Photo-scaled.jpg\" \/>\n\n\t\t\t\t\t<div  class=\"ms-layer  msp-cn-1-6\" style=\"\"      data-ease=\"easeOutQuint\"                data-offset-x=\"0\" data-offset-y=\"0\" data-origin=\"mc\"   >\n<h1 style=\"text-align: center; font-weight: bold; line-height: 75px;\">ELEON<\/h1><h3 style=\"text-align: center; font-weight: 400; line-height: normal;\">Doar energie eolian\u0103 pentru extragerea apei<br \/>din p\u0103m\u00e2nt \u00een scopul irig\u0103rii \u00een agricultura la scar\u0103 mica.<\/h3><\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"6\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/eleon-energy.com\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/eleon-energy.com\/wp-content\/uploads\/2023\/05\/vaci.png\" \/>\n\n\t\t\t\t\t<div  class=\"ms-layer  msp-cn-1-1\" style=\"\"   data-effect=\"t(true,n,n,n,n,n,n,n,n,n,n,n,n,n,n)\" data-duration=\"200\"  data-ease=\"easeOutQuint\"                data-offset-x=\"0\" data-offset-y=\"0\" data-origin=\"mc\" data-phone-offset-x=\"1\" data-phone-offset-y=\"-25\" data-phone-origin=\"mc\" data-relative-size=\"true\"   >\n<h1 style=\"text-align: center; font-weight: bold; line-height: 75px;\">FERMELE MICI<\/h1><h3 style=\"text-align: center; font-weight: 400; line-height: normal;\">Reprezint\u0103 majoritatea substan\u021bial\u0103 a celor <br \/>10 milioane de ferme din Uniunea European\u0103.<\/h3><\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"6\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/eleon-energy.com\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/eleon-energy.com\/wp-content\/uploads\/2023\/05\/Depositphotos_355064478_XL-scaled.jpg\" \/>\n\n\t\t\t\t\t<div  class=\"ms-layer  msp-cn-1-4\" style=\"\"    data-duration=\"200\"  data-ease=\"easeOutQuint\"                data-offset-x=\"0\" data-offset-y=\"0\" data-origin=\"mc\" data-phone-origin=\"mc\"   >\n<h1 style=\"text-align: center; font-weight: bold; line-height: 75px;\">ELEON<\/h1><h3 style=\"text-align: center; font-weight: 400; line-height: normal;\">Solu\u021bie inteligent\u0103, sustenabil\u0103, non-electric\u0103 <br \/>pentru extragerea apei din sol destinat\u0103 agriculturii<br \/>la scar\u0103 mic\u0103.<\/h3><\/div>\n\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t<!-- END MasterSlider Main -->\n\n\t\t\t \n\t\t<\/div>\n\t\t<!-- END MasterSlider -->\n\n\t\t<script>\n\t\t( window.MSReady = window.MSReady || [] ).push( function( $ ) {\n\n\t\t\t\"use strict\";\n\t\t\tvar masterslider_4e02 = new MasterSlider();\n\n\t\t\t\/\/ slider controls\n\t\t\tmasterslider_4e02.control('bullets'    ,{ autohide:false, overVideo:true, dir:'h', align:'bottom', space:5 , margin:10  });\n\t\t\tmasterslider_4e02.control('scrollbar'  ,{ autohide:true, overVideo:true, dir:'h', inset:true, align:'top', color:'#404040' , margin:10  , width:4 });\n\t\t\t\/\/ slider setup\n\t\t\tmasterslider_4e02.setup(\"MS6a57bdf4e4e02\", {\n\t\t\t\twidth           : 800,\n\t\t\t\theight          : 480,\n\t\t\t\tminHeight       : 600,\n\t\t\t\tspace           : 0,\n\t\t\t\tstart           : 1,\n\t\t\t\tgrabCursor      : true,\n\t\t\t\tswipe           : true,\n\t\t\t\tmouse           : true,\n\t\t\t\tkeyboard        : false,\n\t\t\t\tlayout          : \"fullwidth\",\n\t\t\t\twheel           : false,\n\t\t\t\tautoplay        : true,\n                instantStartLayers:false,\n\t\t\t\tmobileBGVideo:false,\n\t\t\t\tloop            : true,\n\t\t\t\tshuffle         : false,\n\t\t\t\tpreload         : 0,\n\t\t\t\theightLimit     : true,\n\t\t\t\tautoHeight      : false,\n\t\t\t\tsmoothHeight    : true,\n\t\t\t\tendPause        : false,\n\t\t\t\toverPause       : false,\n\t\t\t\tfillMode        : \"fill\",\n\t\t\t\tcenterControls  : false,\n\t\t\t\tstartOnAppear   : false,\n\t\t\t\tlayersMode      : \"center\",\n\t\t\t\tautofillTarget  : \"\",\n\t\t\t\thideLayers      : false,\n\t\t\t\tfullscreenMargin: 0,\n\t\t\t\tspeed           : 20,\n\t\t\t\tdir             : \"h\",\n\t\t\t\tresponsive      : true,\n\t\t\t\ttabletWidth     : 768,\n\t\t\t\ttabletHeight    : null,\n\t\t\t\tphoneWidth      : 480,\n\t\t\t\tphoneHeight    : null,\n\t\t\t\tsizingReference : window,\n\t\t\t\tparallaxMode    : 'swipe',\n\t\t\t\tview            : \"basic\"\n\t\t\t});\n\n\t\t\t\n\t\t\twindow.masterslider_instances = window.masterslider_instances || [];\n\t\t\twindow.masterslider_instances.push( masterslider_4e02 );\n\t\t});\n\t\t<\/script>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be8bce3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"be8bce3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-\" data-id=\"\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element- elementor-widget elementor-widget-html\" data-id=\"\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link href=\"https:\/\/font s.googleapis.com\/css2?family=Playfair+Display:ital,wght@0,400;0,700;1,400&display=swap\" rel=\"stylesheet\">\n<div style=\"background:linear-gradient(135deg,#005f57 0%,#24434a 50%,#2a5a62 100%);padding:70px 30px;text-align:center;width:100%;box-sizing:border-box;\">\n  <h2 style=\"font-family:'Playfair Display',Georgia,serif;font-size:54px;color:#f2f0eb;margin:0 0 20px 0;font-weight:700;line-height:1.2;text-shadow:0 2px 15px rgba(0,0,0,0.2);\">Discover AgroDecision AI<\/h2>\n  <p style=\"font-family:Arial,sans-serif;color:rgba(242,240,235,0.88);font-size:18px;margin:0 auto 36px auto;max-width:700px;line-height:1.65;font-weight:300;\">The smart agricultural decision platform: crop recommendations, AI disease diagnosis, an economic calculator, and weather forecasting \u2014 all in one place.<\/p>\n  <a href=\"https:\/\/eleon-energy.com\/ro\/agrodecision-ai\/\" style=\"display:inline-block;background:rgba(242,240,235,0.12);color:#f2f0eb;padding:13px 32px;border-radius:40px;font-size:15px;font-weight:600;text-decoration:none;border:2px solid rgba(242,240,235,0.55);letter-spacing:0.4px;\">Discover the platform \u2192<\/a>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60c809c7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"60c809c7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42b25361\" data-id=\"42b25361\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-29989fb0 elementor-section-full_width skt-ecology-supporters-box elementor-section-height-default elementor-section-height-default\" data-id=\"29989fb0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-40ec4908\" data-id=\"40ec4908\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-105b509 elementor-widget elementor-widget-menu-anchor\" data-id=\"105b509\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.1 - 09-05-2023 *\/\nbody.elementor-page .elementor-widget-menu-anchor{margin-bottom:0}<\/style>\t\t<div class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2281ba34\" data-id=\"2281ba34\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47125757 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"47125757\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.1 - 09-05-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Majoritatea semnificativ\u0103 a celor 600 de <\/br>  milioane de ferme din lume sunt mici.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-765ddb42 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"765ddb42\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">p\u00e2n\u0103 la 2 ha de teren agricol<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-252233fe skt-ecology-section1 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"252233fe\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e02598c skt-ecology-section1-left\" data-id=\"e02598c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d968a elementor-widget elementor-widget-image\" data-id=\"7d968a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.1 - 09-05-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2166\" src=\"https:\/\/eleon-energy.com\/wp-content\/uploads\/2023\/05\/shutterstock_1667113786-scaled.jpg\" class=\"attachment-full size-full wp-image-1787\" alt=\"\" srcset=\"https:\/\/eleon-energy.com\/wp-content\/uploads\/2023\/05\/shutterstock_1667113786-scaled.jpg 2560w, https:\/\/eleon-energy.com\/wp-content\/uploads\/2023\/05\/shutterstock_1667113786-300x254.jpg 300w, https:\/\/eleon-energy.com\/wp-content\/uploads\/2023\/05\/shutterstock_1667113786-768x650.jpg 768w, https:\/\/eleon-energy.com\/wp-content\/uploads\/2023\/05\/shutterstock_1667113786-1024x866.jpg 1024w, https:\/\/eleon-energy.com\/wp-content\/uploads\/2023\/05\/shutterstock_1667113786-1536x1300.jpg 1536w, https:\/\/eleon-energy.com\/wp-content\/uploads\/2023\/05\/shutterstock_1667113786-2048x1733.jpg 2048w, https:\/\/eleon-energy.com\/wp-content\/uploads\/2023\/05\/shutterstock_1667113786-100x84.jpg 100w, https:\/\/eleon-energy.com\/wp-content\/uploads\/2023\/05\/shutterstock_1667113786-14x12.jpg 14w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-51646c91 skt-ecology-section1-counter elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51646c91\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6844da81\" data-id=\"6844da81\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c1e8d1b elementor-widget elementor-widget-heading\" data-id=\"7c1e8d1b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CU 50% MAI MULTE IRIGA\u021aII PENTRU AGRICULTUR\u0102 <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7af096ef elementor-widget elementor-widget-heading\" data-id=\"7af096ef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2050<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7e295b24\" data-id=\"7e295b24\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-47263d47\" data-id=\"47263d47\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7512ec73 elementor-widget elementor-widget-image\" data-id=\"7512ec73\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/eleon-energy.com\/wp-content\/uploads\/elementor\/thumbs\/1074751_4153-removebg-preview-rpebhf0d22zh9kc9intmdt2mg7f0urreejgjfn7tmy.png\" title=\"1074751_4153-removebg-preview\" alt=\"1074751_4153-removebg-preview\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e4f4980 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"1e4f4980\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Apa este vital\u0103 <br>pentru produc\u021bia de alimente<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-528b8319 elementor-widget elementor-widget-text-editor\" data-id=\"528b8319\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.1 - 09-05-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p class=\"p1\">P\u00e2n\u0103 \u00een 2050 se estimeaz\u0103 c\u0103 popula\u021bia lumii va cre\u0219te cu p\u00e2n\u0103 la 10 miliarde de oameni. FAO (Organiza\u021bia Na\u021biunilor Unite pentru Alimenta\u021bie \u0219i Agricultur\u0103) estimeaz\u0103 c\u0103 va fi nevoie de aproximativ 60% mai mult\u0103 hran\u0103, astfel c\u0103 nevoia de ap\u0103 extras\u0103 din sol pentru iriga\u021bii \u00een agricultur\u0103 <strong>va cre\u0219te semnificativ<\/strong>.\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4683cb33 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"4683cb33\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/eleon-energy.com\/ro\/solution\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Cite\u0219te mai mult<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1137652d skt-ecology-section10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1137652d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-74857f01 skt-ecology-section10-left\" data-id=\"74857f01\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-54bb17bf elementor-section-full_width elementor-section-height-min-height elementor-section-height-default\" data-id=\"54bb17bf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1eb6a879\" data-id=\"1eb6a879\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6259de86\" data-id=\"6259de86\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4f4d921 skt-ecology-section10-right\" data-id=\"4f4d921\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-697af461 elementor-widget elementor-widget-heading\" data-id=\"697af461\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O mai bun\u0103 utilizare a resurselor de ap\u0103 <\/br> \u00een agricultura la scar\u0103 mic\u0103<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bbddc14 elementor-widget elementor-widget-text-editor\" data-id=\"2bbddc14\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"p1\">Eleon aduce o solu\u021bie inedit\u0103 de turbin\u0103 eolian\u0103-pomp\u0103 de ap\u0103 sub form\u0103 de kit pentru irigare \u00een agricultura la scar\u0103 mic\u0103. Solu\u021bia se adreseaz\u0103 micilor fermieri, persoanelor fizice, cresc\u0103torilor de animale, iazurilor cu pe\u0219ti \u0219i piscinelor. Nu necesit\u0103 \u00eentre\u021binere special\u0103, are fiabilitate ridicat\u0103 datorit\u0103 faptului c\u0103 este conceput\u0103 cu doar c\u00e2teva p\u0103r\u021bi mobile iar conceptul general este extrem de compact din punct de vedere al sistemelor de ac\u021bionare.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-126e64bd skt-ecology-project-list elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"126e64bd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2e76054 skt-ecology-project-number\" data-id=\"2e76054\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-615b0350 elementor-widget elementor-widget-heading\" data-id=\"615b0350\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">01<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4ce914e4\" data-id=\"4ce914e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1967072e elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"1967072e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Energie regenerabil\u0103 pentru extragerea apei <\/br> din sol \u2013 agricultur\u0103 \u0219i gospod\u0103rii<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1cac6814 skt-ecology-project-list elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cac6814\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6ef69995 skt-ecology-project-number\" data-id=\"6ef69995\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cf1eb74 elementor-widget elementor-widget-heading\" data-id=\"5cf1eb74\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">02<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3f17426e\" data-id=\"3f17426e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ba46c97 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"4ba46c97\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solu\u021bie ecologic\u0103 \u0219i sustenabil\u0103<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-777a00e1 skt-ecology-project-list elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"777a00e1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-45997283 skt-ecology-project-number\" data-id=\"45997283\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25f16728 elementor-widget elementor-widget-heading\" data-id=\"25f16728\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">03<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-645c00c3\" data-id=\"645c00c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-294f3dd5 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"294f3dd5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pre\u021b competitiv; zero consum energie electric\u0103<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5764f090 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5764f090\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-347f590c\" data-id=\"347f590c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-54ef207d elementor-section-full_width elementor-section-height-min-height elementor-section-content-middle elementor-section-height-default\" data-id=\"54ef207d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-395d6f70\" data-id=\"395d6f70\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bc934f8 elementor-widget elementor-widget-heading\" data-id=\"6bc934f8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ENERGIE REGENERABIL\u0102 PENTRU EXTRAGEREA APEI DIN SOL \u00ceN AGRICULTUR\u0102<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20942dce elementor-widget elementor-widget-text-editor\" data-id=\"20942dce\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"p1\">\u021ain\u00e2nd cont de cele 17 Obiective de Dezvoltare Durabil\u0103 ale Organiza\u021biei Na\u021biunilor Unite, conceptul Eleon \u00eendepline\u0219te cel pu\u021bin 2 dintre acestea:<br\/>SDG 7 \u2013 Energie Accesibil\u0103 \u0219i Curat\u0103 \u0219i SDG 12 \u2013 Consum \u0219i Produc\u021bie \u00een mod responsabil.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2028c543\" data-id=\"2028c543\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9223eab elementor-widget elementor-widget-spacer\" data-id=\"9223eab\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.1 - 09-05-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d8b4cd7 skt-ecology-section4 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d8b4cd7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29415fa skt-ecology-section4-left\" data-id=\"29415fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f668692 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f668692\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dabe016\" data-id=\"dabe016\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e56f6b elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"6e56f6b\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.1 - 09-05-2023 *\/\n.elementor-widget-image-box .elementor-image-box-content{width:100%}@media (min-width:768px){.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper,.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{display:flex}.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{text-align:right;flex-direction:row-reverse}.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper{text-align:left;flex-direction:row}.elementor-widget-image-box.elementor-position-top .elementor-image-box-img{margin:auto}.elementor-widget-image-box.elementor-vertical-align-top .elementor-image-box-wrapper{align-items:flex-start}.elementor-widget-image-box.elementor-vertical-align-middle .elementor-image-box-wrapper{align-items:center}.elementor-widget-image-box.elementor-vertical-align-bottom .elementor-image-box-wrapper{align-items:flex-end}}@media (max-width:767px){.elementor-widget-image-box .elementor-image-box-img{margin-left:auto!important;margin-right:auto!important;margin-bottom:15px}}.elementor-widget-image-box .elementor-image-box-img{display:inline-block}.elementor-widget-image-box .elementor-image-box-title a{color:inherit}.elementor-widget-image-box .elementor-image-box-wrapper{text-align:center}.elementor-widget-image-box .elementor-image-box-description{margin:0}<\/style><div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Contacteaz\u0103-ne<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5112d6f0 skt-ecology-section4-right\" data-id=\"5112d6f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c6a0b6b elementor-mobile-align-center elementor-align-right elementor-widget elementor-widget-button\" data-id=\"4c6a0b6b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/eleon-energy.com\/ro\/contact\/\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTACT<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Discover AgroDecision AI The smart agricultural decision platform: crop recommendations, AI disease diagnosis, an economic calculator, and weather forecasting \u2014 all in one place. Discover the platform \u2192 Significant majority of the world&#8217;s 600 million farms are small up to 2 ha of farmland 50% MORE IRRIGATED FOOD PRODUCTION BY 2050 Water is vital for<br \/><a class=\"moretag\" href=\"https:\/\/eleon-energy.com\/ro\/\">+ Read More<\/a><\/p>","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/page-builder.php","meta":{"footnotes":""},"class_list":["post-8","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Home - Eleon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eleon-energy.com\/ro\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Eleon\" \/>\n<meta property=\"og:description\" content=\"Discover AgroDecision AI The smart agricultural decision platform: crop recommendations, AI disease diagnosis, an economic calculator, and weather forecasting \u2014 all in one place. Discover the platform \u2192 Significant majority of the world&#8217;s 600 million farms are small up to 2 ha of farmland 50% MORE IRRIGATED FOOD PRODUCTION BY 2050 Water is vital for+ Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eleon-energy.com\/ro\/\" \/>\n<meta property=\"og:site_name\" content=\"Eleon\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T06:53:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eleon-energy.com\/wp-content\/uploads\/2023\/05\/shutterstock_1667113786-scaled.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eleon-energy.com\/\",\"url\":\"https:\/\/eleon-energy.com\/\",\"name\":\"Home - Eleon\",\"isPartOf\":{\"@id\":\"https:\/\/eleon-energy.com\/ro\/#website\"},\"datePublished\":\"2022-02-22T07:58:25+00:00\",\"dateModified\":\"2026-06-25T06:53:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eleon-energy.com\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eleon-energy.com\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eleon-energy.com\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eleon-energy.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eleon-energy.com\/ro\/#website\",\"url\":\"https:\/\/eleon-energy.com\/ro\/\",\"name\":\"Eleon\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eleon-energy.com\/ro\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - Eleon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eleon-energy.com\/ro\/","og_locale":"ro_RO","og_type":"article","og_title":"Home - Eleon","og_description":"Discover AgroDecision AI The smart agricultural decision platform: crop recommendations, AI disease diagnosis, an economic calculator, and weather forecasting \u2014 all in one place. Discover the platform \u2192 Significant majority of the world&#8217;s 600 million farms are small up to 2 ha of farmland 50% MORE IRRIGATED FOOD PRODUCTION BY 2050 Water is vital for+ Read More","og_url":"https:\/\/eleon-energy.com\/ro\/","og_site_name":"Eleon","article_modified_time":"2026-06-25T06:53:20+00:00","og_image":[{"url":"https:\/\/eleon-energy.com\/wp-content\/uploads\/2023\/05\/shutterstock_1667113786-scaled.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Timp estimat pentru citire":"2 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eleon-energy.com\/","url":"https:\/\/eleon-energy.com\/","name":"Home - Eleon","isPartOf":{"@id":"https:\/\/eleon-energy.com\/ro\/#website"},"datePublished":"2022-02-22T07:58:25+00:00","dateModified":"2026-06-25T06:53:20+00:00","breadcrumb":{"@id":"https:\/\/eleon-energy.com\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eleon-energy.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eleon-energy.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eleon-energy.com\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/eleon-energy.com\/ro\/#website","url":"https:\/\/eleon-energy.com\/ro\/","name":"Eleon","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eleon-energy.com\/ro\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/eleon-energy.com\/ro\/wp-json\/wp\/v2\/pages\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eleon-energy.com\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eleon-energy.com\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eleon-energy.com\/ro\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/eleon-energy.com\/ro\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":688,"href":"https:\/\/eleon-energy.com\/ro\/wp-json\/wp\/v2\/pages\/8\/revisions"}],"predecessor-version":[{"id":4423,"href":"https:\/\/eleon-energy.com\/ro\/wp-json\/wp\/v2\/pages\/8\/revisions\/4423"}],"wp:attachment":[{"href":"https:\/\/eleon-energy.com\/ro\/wp-json\/wp\/v2\/media?parent=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}